{"id":2643,"date":"2020-03-21T12:11:32","date_gmt":"2020-03-21T17:11:32","guid":{"rendered":"http:\/\/www.codigovidrio.com\/code\/?p=2643"},"modified":"2020-04-01T15:58:56","modified_gmt":"2020-04-01T20:58:56","slug":"los-californianos-han-empezado-a-entrar-en-panico-y-ha-generar-desabastecimiento-de-alimentos","status":"publish","type":"post","link":"https:\/\/www.codigovidrio.com\/code\/los-californianos-han-empezado-a-entrar-en-panico-y-ha-generar-desabastecimiento-de-alimentos\/","title":{"rendered":"PODCAST: En California hay desabastecimiento de alimentos"},"content":{"rendered":"<p><strong>Diego Arroyo, quite\u00f1o, vive con su familia en Covina, cerca a Los \u00c1ngeles, California, desde hace cuarenta a\u00f1os. Trabaja en el sector de transporte escolar. Este es su testimonio, acompa\u00f1ado por una de sus canciones favoritas.<\/strong><\/p>\n<p><em>Redacci\u00f3n C\u00f3digo Vidrio<\/em><\/p>\n<p>\u201cDesde el viernes pasado, en la empresa donde trabajo de transporte escolar para ni\u00f1os con capacidades especiales, suspendieron todas las actividades, porque las escuelas, colegios y universidades tambi\u00e9n cerraron por el coronavirus.<\/p>\n<p>[spreaker type=player resource=\u00bbepisode_id=24139118&#8243; width=\u00bb100%\u00bb height=\u00bb200px\u00bb theme=\u00bblight\u00bb playlist=\u00bbfalse\u00bb playlist-continuous=\u00bbfalse\u00bb autoplay=\u00bbfalse\u00bb live-autoplay=\u00bbfalse\u00bb chapters-image=\u00bbtrue\u00bb episode-image-position=\u00bbright\u00bb hide-logo=\u00bbfalse\u00bb hide-likes=\u00bbfalse\u00bb hide-comments=\u00bbfalse\u00bb hide-sharing=\u00bbfalse\u00bb hide-download=\u00bbtrue\u00bb]<\/p>\n<p>&nbsp;<\/p>\n<p>Estamos con vacaciones forzadas. Ac\u00e1, en general, los californianos han tomado la emergencia por la pandemia de forma relajada, a la ligera.<\/p>\n<p>La mayor\u00eda de la poblaci\u00f3n no tom\u00f3 precauciones a tiempo, y hay descoordinaciones entre las autoridades del estado de California con los funcionarios federales, encabezados por el presidente Donald Trump. La m\u00e1xima autoridad ac\u00e1 es el gobernador.<\/p>\n<p>Con los d\u00edas, la gente ha empezado a entender la gravedad del problema que enfrentamos. Nosotros nos aprovisionamos de v\u00edveres e insumos las semanas pasadas, pero buena parte de los habitantes no, dejaron todo para el \u00faltimo momento, por eso los grandes mercados est\u00e1n totalmente desabastecidos, hay gente que est\u00e1 acaparando alimentos.<\/p>\n<p>El Gobierno central tiene poca posibilidad de exigir normas a los habitantes de cada estado, no hay forma de obligarlos a aislarse en sus casas, a no ser que salgan militares a las calles, pero cada estado toma al final esa decisi\u00f3n.<\/p>\n<p>La principal amenaza de que el contagio se extienda r\u00e1pidamente es la ligereza de la poblaci\u00f3n, que tomaba las cosas con mucha calma, estaban muy relajados, as\u00ed son los californianos, pero los \u00faltimos d\u00edas empezaron a entrar en p\u00e1nico.<\/p>\n<p>Solo mi yerno y mi hijo est\u00e1n trabajando en mi familia, porque se dedican a instalar tecnolog\u00eda para la casa, y eso tiene mucha demanda. El resto no estamos laborando.<\/p>\n<p>Pese a las alertas, las calles se ven con circulaci\u00f3n normal. Hay problemas en los servicios m\u00e9dicos de salud, incluso no hay no reactivos para hacer las pruebas del Coronavirus.<\/p>\n<p>Este asilamiento tiene tambi\u00e9n un lado positivo, pues nos da la oportunidad de meditar sobre lo que est\u00e1 ocurriendo, y tener consciencia de que somos privilegiados porque contamos con un techo y previsiones para mantenernos, mientras dure esta emergencia.<\/p>\n<p>No ocurre lo mismo con la gente que no cuenta con recursos y vive en las calles, o quienes no tienen empleos formales, viven de su jornada del d\u00eda, sino trabajan no comen; no tienen seguro de desempleo ni salud, est\u00e1n desamparados.<\/p>\n<p>Esta es una oportunidad para ayudar a los m\u00e1s vulnerables y desprotegidos, entre quienes hay muchos migrantes\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Diego Arroyo, quite\u00f1o, vive con su familia en Covina, cerca a Los \u00c1ngeles, California, desde hace cuarenta a\u00f1os. Trabaja en el sector de transporte escolar. Este es su testimonio, acompa\u00f1ado por una de sus canciones favoritas. Redacci\u00f3n C\u00f3digo Vidrio \u201cDesde el viernes pasado, en la empresa donde trabajo de transporte escolar para ni\u00f1os con capacidades &#8230; <a title=\"PODCAST: En California hay desabastecimiento de alimentos\" class=\"read-more\" href=\"https:\/\/www.codigovidrio.com\/code\/los-californianos-han-empezado-a-entrar-en-panico-y-ha-generar-desabastecimiento-de-alimentos\/\">leer m\u00e1s&#8230;<\/a><\/p>\n","protected":false},"author":2,"featured_media":2644,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"generate_page_header":"","footnotes":""},"categories":[217],"tags":[],"class_list":["post-2643","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-podcast"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>PODCAST: En California hay desabastecimiento de alimentos - C\u00f3digo Vidrio<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.codigovidrio.com\/code\/los-californianos-han-empezado-a-entrar-en-panico-y-ha-generar-desabastecimiento-de-alimentos\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"PODCAST: En California hay desabastecimiento de alimentos - C\u00f3digo Vidrio\" \/>\n<meta property=\"og:description\" content=\"Diego Arroyo, quite\u00f1o, vive con su familia en Covina, cerca a Los \u00c1ngeles, California, desde hace cuarenta a\u00f1os. Trabaja en el sector de transporte escolar. Este es su testimonio, acompa\u00f1ado por una de sus canciones favoritas. Redacci\u00f3n C\u00f3digo Vidrio \u201cDesde el viernes pasado, en la empresa donde trabajo de transporte escolar para ni\u00f1os con capacidades ... leer m\u00e1s...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.codigovidrio.com\/code\/los-californianos-han-empezado-a-entrar-en-panico-y-ha-generar-desabastecimiento-de-alimentos\/\" \/>\n<meta property=\"og:site_name\" content=\"C\u00f3digo Vidrio\" \/>\n<meta property=\"article:published_time\" content=\"2020-03-21T17:11:32+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-04-01T20:58:56+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.codigovidrio.com\/code\/wp-content\/uploads\/2020\/03\/pc-4-head.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"650\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Codigo Vidrio Admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Codigo Vidrio Admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.codigovidrio.com\\\/code\\\/los-californianos-han-empezado-a-entrar-en-panico-y-ha-generar-desabastecimiento-de-alimentos\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.codigovidrio.com\\\/code\\\/los-californianos-han-empezado-a-entrar-en-panico-y-ha-generar-desabastecimiento-de-alimentos\\\/\"},\"author\":{\"name\":\"Codigo Vidrio Admin\",\"@id\":\"https:\\\/\\\/www.codigovidrio.com\\\/code\\\/#\\\/schema\\\/person\\\/974bc7a5b889699d012b2343dc68fc6e\"},\"headline\":\"PODCAST: En California hay desabastecimiento de alimentos\",\"datePublished\":\"2020-03-21T17:11:32+00:00\",\"dateModified\":\"2020-04-01T20:58:56+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.codigovidrio.com\\\/code\\\/los-californianos-han-empezado-a-entrar-en-panico-y-ha-generar-desabastecimiento-de-alimentos\\\/\"},\"wordCount\":488,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.codigovidrio.com\\\/code\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.codigovidrio.com\\\/code\\\/los-californianos-han-empezado-a-entrar-en-panico-y-ha-generar-desabastecimiento-de-alimentos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.codigovidrio.com\\\/code\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/pc-4-head.jpg\",\"articleSection\":[\"Podcast\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.codigovidrio.com\\\/code\\\/los-californianos-han-empezado-a-entrar-en-panico-y-ha-generar-desabastecimiento-de-alimentos\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.codigovidrio.com\\\/code\\\/los-californianos-han-empezado-a-entrar-en-panico-y-ha-generar-desabastecimiento-de-alimentos\\\/\",\"url\":\"https:\\\/\\\/www.codigovidrio.com\\\/code\\\/los-californianos-han-empezado-a-entrar-en-panico-y-ha-generar-desabastecimiento-de-alimentos\\\/\",\"name\":\"PODCAST: En California hay desabastecimiento de alimentos - C\u00f3digo Vidrio\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.codigovidrio.com\\\/code\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.codigovidrio.com\\\/code\\\/los-californianos-han-empezado-a-entrar-en-panico-y-ha-generar-desabastecimiento-de-alimentos\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.codigovidrio.com\\\/code\\\/los-californianos-han-empezado-a-entrar-en-panico-y-ha-generar-desabastecimiento-de-alimentos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.codigovidrio.com\\\/code\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/pc-4-head.jpg\",\"datePublished\":\"2020-03-21T17:11:32+00:00\",\"dateModified\":\"2020-04-01T20:58:56+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.codigovidrio.com\\\/code\\\/los-californianos-han-empezado-a-entrar-en-panico-y-ha-generar-desabastecimiento-de-alimentos\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.codigovidrio.com\\\/code\\\/los-californianos-han-empezado-a-entrar-en-panico-y-ha-generar-desabastecimiento-de-alimentos\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.codigovidrio.com\\\/code\\\/los-californianos-han-empezado-a-entrar-en-panico-y-ha-generar-desabastecimiento-de-alimentos\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.codigovidrio.com\\\/code\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/pc-4-head.jpg\",\"contentUrl\":\"https:\\\/\\\/www.codigovidrio.com\\\/code\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/pc-4-head.jpg\",\"width\":1600,\"height\":650},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.codigovidrio.com\\\/code\\\/los-californianos-han-empezado-a-entrar-en-panico-y-ha-generar-desabastecimiento-de-alimentos\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.codigovidrio.com\\\/code\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"PODCAST: En California hay desabastecimiento de alimentos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.codigovidrio.com\\\/code\\\/#website\",\"url\":\"https:\\\/\\\/www.codigovidrio.com\\\/code\\\/\",\"name\":\"C\u00f3digo Vidrio\",\"description\":\"Transparentamos las historias ocultas\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.codigovidrio.com\\\/code\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.codigovidrio.com\\\/code\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.codigovidrio.com\\\/code\\\/#organization\",\"name\":\"C\u00f3digo Vidrio\",\"url\":\"https:\\\/\\\/www.codigovidrio.com\\\/code\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.codigovidrio.com\\\/code\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.codigovidrio.com\\\/code\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/logo-horiz-08.png\",\"contentUrl\":\"https:\\\/\\\/www.codigovidrio.com\\\/code\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/logo-horiz-08.png\",\"width\":817,\"height\":294,\"caption\":\"C\u00f3digo Vidrio\"},\"image\":{\"@id\":\"https:\\\/\\\/www.codigovidrio.com\\\/code\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.codigovidrio.com\\\/code\\\/#\\\/schema\\\/person\\\/974bc7a5b889699d012b2343dc68fc6e\",\"name\":\"Codigo Vidrio Admin\",\"url\":\"https:\\\/\\\/www.codigovidrio.com\\\/code\\\/author\\\/vidrio-admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"PODCAST: En California hay desabastecimiento de alimentos - C\u00f3digo Vidrio","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.codigovidrio.com\/code\/los-californianos-han-empezado-a-entrar-en-panico-y-ha-generar-desabastecimiento-de-alimentos\/","og_locale":"es_ES","og_type":"article","og_title":"PODCAST: En California hay desabastecimiento de alimentos - C\u00f3digo Vidrio","og_description":"Diego Arroyo, quite\u00f1o, vive con su familia en Covina, cerca a Los \u00c1ngeles, California, desde hace cuarenta a\u00f1os. Trabaja en el sector de transporte escolar. Este es su testimonio, acompa\u00f1ado por una de sus canciones favoritas. Redacci\u00f3n C\u00f3digo Vidrio \u201cDesde el viernes pasado, en la empresa donde trabajo de transporte escolar para ni\u00f1os con capacidades ... leer m\u00e1s...","og_url":"https:\/\/www.codigovidrio.com\/code\/los-californianos-han-empezado-a-entrar-en-panico-y-ha-generar-desabastecimiento-de-alimentos\/","og_site_name":"C\u00f3digo Vidrio","article_published_time":"2020-03-21T17:11:32+00:00","article_modified_time":"2020-04-01T20:58:56+00:00","og_image":[{"width":1600,"height":650,"url":"https:\/\/www.codigovidrio.com\/code\/wp-content\/uploads\/2020\/03\/pc-4-head.jpg","type":"image\/jpeg"}],"author":"Codigo Vidrio Admin","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Codigo Vidrio Admin","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.codigovidrio.com\/code\/los-californianos-han-empezado-a-entrar-en-panico-y-ha-generar-desabastecimiento-de-alimentos\/#article","isPartOf":{"@id":"https:\/\/www.codigovidrio.com\/code\/los-californianos-han-empezado-a-entrar-en-panico-y-ha-generar-desabastecimiento-de-alimentos\/"},"author":{"name":"Codigo Vidrio Admin","@id":"https:\/\/www.codigovidrio.com\/code\/#\/schema\/person\/974bc7a5b889699d012b2343dc68fc6e"},"headline":"PODCAST: En California hay desabastecimiento de alimentos","datePublished":"2020-03-21T17:11:32+00:00","dateModified":"2020-04-01T20:58:56+00:00","mainEntityOfPage":{"@id":"https:\/\/www.codigovidrio.com\/code\/los-californianos-han-empezado-a-entrar-en-panico-y-ha-generar-desabastecimiento-de-alimentos\/"},"wordCount":488,"commentCount":0,"publisher":{"@id":"https:\/\/www.codigovidrio.com\/code\/#organization"},"image":{"@id":"https:\/\/www.codigovidrio.com\/code\/los-californianos-han-empezado-a-entrar-en-panico-y-ha-generar-desabastecimiento-de-alimentos\/#primaryimage"},"thumbnailUrl":"https:\/\/www.codigovidrio.com\/code\/wp-content\/uploads\/2020\/03\/pc-4-head.jpg","articleSection":["Podcast"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.codigovidrio.com\/code\/los-californianos-han-empezado-a-entrar-en-panico-y-ha-generar-desabastecimiento-de-alimentos\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.codigovidrio.com\/code\/los-californianos-han-empezado-a-entrar-en-panico-y-ha-generar-desabastecimiento-de-alimentos\/","url":"https:\/\/www.codigovidrio.com\/code\/los-californianos-han-empezado-a-entrar-en-panico-y-ha-generar-desabastecimiento-de-alimentos\/","name":"PODCAST: En California hay desabastecimiento de alimentos - C\u00f3digo Vidrio","isPartOf":{"@id":"https:\/\/www.codigovidrio.com\/code\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.codigovidrio.com\/code\/los-californianos-han-empezado-a-entrar-en-panico-y-ha-generar-desabastecimiento-de-alimentos\/#primaryimage"},"image":{"@id":"https:\/\/www.codigovidrio.com\/code\/los-californianos-han-empezado-a-entrar-en-panico-y-ha-generar-desabastecimiento-de-alimentos\/#primaryimage"},"thumbnailUrl":"https:\/\/www.codigovidrio.com\/code\/wp-content\/uploads\/2020\/03\/pc-4-head.jpg","datePublished":"2020-03-21T17:11:32+00:00","dateModified":"2020-04-01T20:58:56+00:00","breadcrumb":{"@id":"https:\/\/www.codigovidrio.com\/code\/los-californianos-han-empezado-a-entrar-en-panico-y-ha-generar-desabastecimiento-de-alimentos\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.codigovidrio.com\/code\/los-californianos-han-empezado-a-entrar-en-panico-y-ha-generar-desabastecimiento-de-alimentos\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.codigovidrio.com\/code\/los-californianos-han-empezado-a-entrar-en-panico-y-ha-generar-desabastecimiento-de-alimentos\/#primaryimage","url":"https:\/\/www.codigovidrio.com\/code\/wp-content\/uploads\/2020\/03\/pc-4-head.jpg","contentUrl":"https:\/\/www.codigovidrio.com\/code\/wp-content\/uploads\/2020\/03\/pc-4-head.jpg","width":1600,"height":650},{"@type":"BreadcrumbList","@id":"https:\/\/www.codigovidrio.com\/code\/los-californianos-han-empezado-a-entrar-en-panico-y-ha-generar-desabastecimiento-de-alimentos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.codigovidrio.com\/code\/"},{"@type":"ListItem","position":2,"name":"PODCAST: En California hay desabastecimiento de alimentos"}]},{"@type":"WebSite","@id":"https:\/\/www.codigovidrio.com\/code\/#website","url":"https:\/\/www.codigovidrio.com\/code\/","name":"C\u00f3digo Vidrio","description":"Transparentamos las historias ocultas","publisher":{"@id":"https:\/\/www.codigovidrio.com\/code\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.codigovidrio.com\/code\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.codigovidrio.com\/code\/#organization","name":"C\u00f3digo Vidrio","url":"https:\/\/www.codigovidrio.com\/code\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.codigovidrio.com\/code\/#\/schema\/logo\/image\/","url":"https:\/\/www.codigovidrio.com\/code\/wp-content\/uploads\/2022\/01\/logo-horiz-08.png","contentUrl":"https:\/\/www.codigovidrio.com\/code\/wp-content\/uploads\/2022\/01\/logo-horiz-08.png","width":817,"height":294,"caption":"C\u00f3digo Vidrio"},"image":{"@id":"https:\/\/www.codigovidrio.com\/code\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.codigovidrio.com\/code\/#\/schema\/person\/974bc7a5b889699d012b2343dc68fc6e","name":"Codigo Vidrio Admin","url":"https:\/\/www.codigovidrio.com\/code\/author\/vidrio-admin\/"}]}},"_links":{"self":[{"href":"https:\/\/www.codigovidrio.com\/code\/wp-json\/wp\/v2\/posts\/2643","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.codigovidrio.com\/code\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.codigovidrio.com\/code\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.codigovidrio.com\/code\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.codigovidrio.com\/code\/wp-json\/wp\/v2\/comments?post=2643"}],"version-history":[{"count":11,"href":"https:\/\/www.codigovidrio.com\/code\/wp-json\/wp\/v2\/posts\/2643\/revisions"}],"predecessor-version":[{"id":2691,"href":"https:\/\/www.codigovidrio.com\/code\/wp-json\/wp\/v2\/posts\/2643\/revisions\/2691"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.codigovidrio.com\/code\/wp-json\/wp\/v2\/media\/2644"}],"wp:attachment":[{"href":"https:\/\/www.codigovidrio.com\/code\/wp-json\/wp\/v2\/media?parent=2643"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.codigovidrio.com\/code\/wp-json\/wp\/v2\/categories?post=2643"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.codigovidrio.com\/code\/wp-json\/wp\/v2\/tags?post=2643"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}